{"id":590,"date":"2022-08-31T15:29:17","date_gmt":"2022-08-31T15:29:17","guid":{"rendered":"https:\/\/muirhevnamore.ie\/?page_id=590"},"modified":"2022-11-11T01:28:22","modified_gmt":"2022-11-11T01:28:22","slug":"drawings-architecture","status":"publish","type":"page","link":"https:\/\/lrdwebsite.ie\/template1\/drawings-architecture\/","title":{"rendered":"Drawings &#8211; Architecture"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"590\" class=\"elementor elementor-590\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0921d90 elementor-section-full_width contentScreen elementor-section-height-default elementor-section-height-default\" data-id=\"0921d90\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11bc540\" data-id=\"11bc540\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-77a2001 elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default\" data-id=\"77a2001\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a3d5e50\" data-id=\"a3d5e50\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-824771a elementor-widget elementor-widget-heading\" data-id=\"824771a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.0 - 30-10-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Architecture<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cc04553 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc04553\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8be7a08\" data-id=\"8be7a08\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35315af elementor-widget elementor-widget-spacer\" data-id=\"35315af\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.0 - 30-10-2022 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));-ms-flex-item-align:stretch;align-self:stretch;-ms-flex-negative:0;flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68753a7 elementor-widget elementor-widget-spacer\" data-id=\"68753a7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6d9400 elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"b6d9400\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor10025 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor10025 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor10025 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor10025 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor10025 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor10025 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor10025\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Site Location Map<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc51e6d elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"fc51e6d\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor23167 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor23167 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor23167 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor23167 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor23167 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor23167 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor23167\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Site Layout Plan<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f027bd elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"9f027bd\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor38012 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor38012 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor38012 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor38012 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor38012 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor38012 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor38012\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Site Sections Sheet 01<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2f582d elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"c2f582d\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor47610 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor47610 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor47610 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor47610 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor47610 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor47610 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor47610\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Site Sections Sheet 02<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-906a52f elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"906a52f\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor55439 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor55439 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor55439 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor55439 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor55439 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor55439 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor55439\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Site Sections Sheet 03<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74e093b elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"74e093b\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor61012 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor61012 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor61012 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor61012 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor61012 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor61012 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor61012\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Master Plan<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a68473a elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"a68473a\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor70598 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor70598 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor70598 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor70598 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor70598 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor70598 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor70598\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Public Realm<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1f5c3a elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"a1f5c3a\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor86853 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor86853 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor86853 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor86853 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor86853 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor86853 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor86853\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Parking Roads<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5374730 elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"5374730\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor95843 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor95843 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor95843 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor95843 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor95843 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor95843 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor95843\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Private OS<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a992e1a elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"a992e1a\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor103999 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor103999 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor103999 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor103999 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor103999 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor103999 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor103999\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Connectivity<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f92ca44 elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"f92ca44\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor117524 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor117524 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor117524 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor117524 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor117524 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor117524 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor117524\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Bin-Cycle Storage<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-508fc4c elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"508fc4c\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor128934 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor128934 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor128934 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor128934 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor128934 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor128934 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor128934\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Phasing<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-615fffd elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"615fffd\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor132911 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor132911 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor132911 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor132911 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor132911 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor132911 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor132911\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Boundary Details<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7908aa elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"a7908aa\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor148267 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor148267 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor148267 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor148267 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor148267 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor148267 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor148267\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Type A - 2Bed Terraced<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8a35ac elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"d8a35ac\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor159076 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor159076 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor159076 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor159076 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor159076 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor159076 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor159076\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Type B - 3Bed Terraced<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc084ab elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"bc084ab\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor164613 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor164613 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor164613 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor164613 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor164613 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor164613 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor164613\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Type C - 3Bed Semi D<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-669506a elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"669506a\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor179573 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor179573 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor179573 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor179573 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor179573 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor179573 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor179573\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Type C&D - 3Bed Semi D<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-706c2c7 elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"706c2c7\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor186098 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor186098 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor186098 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor186098 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor186098 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor186098 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor186098\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Block A Plans<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67abd28 elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"67abd28\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor198560 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor198560 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor198560 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor198560 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor198560 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor198560 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor198560\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Block A Elevations<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a9af86 elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"4a9af86\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor202999 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor202999 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor202999 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor202999 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor202999 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor202999 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor202999\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Block B plans<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d93da55 elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"d93da55\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor213443 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor213443 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor213443 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor213443 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor213443 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor213443 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor213443\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Block B Elevations<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d55cbdc elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"d55cbdc\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor227272 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor227272 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor227272 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor227272 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor227272 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor227272 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor227272\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Block C plans<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d54499 elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"9d54499\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor230202 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor230202 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor230202 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor230202 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor230202 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor230202 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor230202\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Block C Elevations<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bc1d65 elementor-widget elementor-widget-spacer\" data-id=\"6bc1d65\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e5716d elementor-widget elementor-widget-spacer\" data-id=\"3e5716d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Architecture Site Location Map Site Layout Plan Site Sections Sheet 01 Site Sections Sheet 02 Site Sections Sheet 03 Master Plan Public Realm Parking Roads Private OS Connectivity Bin-Cycle Storage Phasing Boundary Details Type A &#8211; 2Bed Terraced Type B &#8211; 3Bed Terraced Type C &#8211; 3Bed Semi D Type C&#038;D &#8211; 3Bed Semi D [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-590","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Drawings - Architecture - LRD Website Template<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lrdwebsite.ie\/template1\/drawings-architecture\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Drawings - Architecture - LRD Website Template\" \/>\n<meta property=\"og:description\" content=\"Architecture Site Location Map Site Layout Plan Site Sections Sheet 01 Site Sections Sheet 02 Site Sections Sheet 03 Master Plan Public Realm Parking Roads Private OS Connectivity Bin-Cycle Storage Phasing Boundary Details Type A &#8211; 2Bed Terraced Type B &#8211; 3Bed Terraced Type C &#8211; 3Bed Semi D Type C&#038;D &#8211; 3Bed Semi D [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lrdwebsite.ie\/template1\/drawings-architecture\/\" \/>\n<meta property=\"og:site_name\" content=\"LRD Website Template\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-11T01:28:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lrdwebsite.ie\/template1\/drawings-architecture\/\",\"url\":\"https:\/\/lrdwebsite.ie\/template1\/drawings-architecture\/\",\"name\":\"Drawings - Architecture - LRD Website Template\",\"isPartOf\":{\"@id\":\"https:\/\/lrdwebsite.ie\/template1\/#website\"},\"datePublished\":\"2022-08-31T15:29:17+00:00\",\"dateModified\":\"2022-11-11T01:28:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lrdwebsite.ie\/template1\/drawings-architecture\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lrdwebsite.ie\/template1\/drawings-architecture\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lrdwebsite.ie\/template1\/drawings-architecture\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/lrdwebsite.ie\/template1\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Drawings &#8211; Architecture\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lrdwebsite.ie\/template1\/#website\",\"url\":\"https:\/\/lrdwebsite.ie\/template1\/\",\"name\":\"LRD Website Template\",\"description\":\"LRD Website Template\",\"publisher\":{\"@id\":\"https:\/\/lrdwebsite.ie\/template1\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lrdwebsite.ie\/template1\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lrdwebsite.ie\/template1\/#organization\",\"name\":\"LRD Website Template\",\"url\":\"https:\/\/lrdwebsite.ie\/template1\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lrdwebsite.ie\/template1\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/Logo-top.png\",\"contentUrl\":\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/Logo-top.png\",\"width\":100,\"height\":21,\"caption\":\"LRD Website Template\"},\"image\":{\"@id\":\"https:\/\/lrdwebsite.ie\/template1\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Drawings - Architecture - LRD Website Template","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lrdwebsite.ie\/template1\/drawings-architecture\/","og_locale":"en_US","og_type":"article","og_title":"Drawings - Architecture - LRD Website Template","og_description":"Architecture Site Location Map Site Layout Plan Site Sections Sheet 01 Site Sections Sheet 02 Site Sections Sheet 03 Master Plan Public Realm Parking Roads Private OS Connectivity Bin-Cycle Storage Phasing Boundary Details Type A &#8211; 2Bed Terraced Type B &#8211; 3Bed Terraced Type C &#8211; 3Bed Semi D Type C&#038;D &#8211; 3Bed Semi D [&hellip;]","og_url":"https:\/\/lrdwebsite.ie\/template1\/drawings-architecture\/","og_site_name":"LRD Website Template","article_modified_time":"2022-11-11T01:28:22+00:00","og_image":[{"url":"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lrdwebsite.ie\/template1\/drawings-architecture\/","url":"https:\/\/lrdwebsite.ie\/template1\/drawings-architecture\/","name":"Drawings - Architecture - LRD Website Template","isPartOf":{"@id":"https:\/\/lrdwebsite.ie\/template1\/#website"},"datePublished":"2022-08-31T15:29:17+00:00","dateModified":"2022-11-11T01:28:22+00:00","breadcrumb":{"@id":"https:\/\/lrdwebsite.ie\/template1\/drawings-architecture\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lrdwebsite.ie\/template1\/drawings-architecture\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lrdwebsite.ie\/template1\/drawings-architecture\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lrdwebsite.ie\/template1\/"},{"@type":"ListItem","position":2,"name":"Drawings &#8211; Architecture"}]},{"@type":"WebSite","@id":"https:\/\/lrdwebsite.ie\/template1\/#website","url":"https:\/\/lrdwebsite.ie\/template1\/","name":"LRD Website Template","description":"LRD Website Template","publisher":{"@id":"https:\/\/lrdwebsite.ie\/template1\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lrdwebsite.ie\/template1\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lrdwebsite.ie\/template1\/#organization","name":"LRD Website Template","url":"https:\/\/lrdwebsite.ie\/template1\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lrdwebsite.ie\/template1\/#\/schema\/logo\/image\/","url":"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/Logo-top.png","contentUrl":"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/Logo-top.png","width":100,"height":21,"caption":"LRD Website Template"},"image":{"@id":"https:\/\/lrdwebsite.ie\/template1\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lrdwebsite.ie\/template1\/wp-json\/wp\/v2\/pages\/590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lrdwebsite.ie\/template1\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lrdwebsite.ie\/template1\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lrdwebsite.ie\/template1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lrdwebsite.ie\/template1\/wp-json\/wp\/v2\/comments?post=590"}],"version-history":[{"count":14,"href":"https:\/\/lrdwebsite.ie\/template1\/wp-json\/wp\/v2\/pages\/590\/revisions"}],"predecessor-version":[{"id":849,"href":"https:\/\/lrdwebsite.ie\/template1\/wp-json\/wp\/v2\/pages\/590\/revisions\/849"}],"wp:attachment":[{"href":"https:\/\/lrdwebsite.ie\/template1\/wp-json\/wp\/v2\/media?parent=590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}