{"id":642,"date":"2022-08-31T15:54:56","date_gmt":"2022-08-31T15:54:56","guid":{"rendered":"https:\/\/muirhevnamore.ie\/?page_id=642"},"modified":"2022-11-11T01:30:14","modified_gmt":"2022-11-11T01:30:14","slug":"drawings-engineering","status":"publish","type":"page","link":"https:\/\/lrdwebsite.ie\/template1\/drawings-engineering\/","title":{"rendered":"Drawings &#8211; Engineering"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"642\" class=\"elementor elementor-642\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0921d90 elementor-section-full_width contentScreen elementor-section-height-default elementor-section-height-default\" data-id=\"0921d90\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11bc540\" data-id=\"11bc540\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-77a2001 elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default\" data-id=\"77a2001\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a3d5e50\" data-id=\"a3d5e50\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-824771a elementor-widget elementor-widget-heading\" data-id=\"824771a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.0 - 30-10-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Engineering<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cc04553 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc04553\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8be7a08\" data-id=\"8be7a08\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35315af elementor-widget elementor-widget-spacer\" data-id=\"35315af\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.0 - 30-10-2022 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));-ms-flex-item-align:stretch;align-self:stretch;-ms-flex-negative:0;flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68753a7 elementor-widget elementor-widget-spacer\" data-id=\"68753a7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6d9400 elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"b6d9400\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor16034 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor16034 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor16034 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor16034 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor16034 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor16034 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor16034\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">P01 Proposed Site Layout<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c049fb4 elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"c049fb4\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor25701 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor25701 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor25701 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor25701 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor25701 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor25701 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor25701\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">P02 Proposed Site Drainage<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc51e6d elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"fc51e6d\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor37706 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor37706 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor37706 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor37706 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor37706 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor37706 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor37706\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">P02 Watermain Layout<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f027bd elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"9f027bd\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor49258 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor49258 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor49258 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor49258 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor49258 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor49258 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor49258\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">P01 Proposed Site Levels<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2f582d elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"c2f582d\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor59122 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor59122 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor59122 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor59122 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor59122 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor59122 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor59122\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">P02 Road Longsections, Sheet 1 of 5<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-906a52f elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"906a52f\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor66181 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor66181 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor66181 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor66181 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor66181 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor66181 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor66181\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">P02 Road Longsections, Sheet 2 of 5<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74e093b elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"74e093b\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor74119 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor74119 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor74119 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor74119 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor74119 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor74119 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor74119\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">P02 Road Longsections, Sheet 3 of 5<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a68473a elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"a68473a\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor85085 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor85085 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor85085 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor85085 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor85085 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor85085 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor85085\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">P02 Road Longsections, Sheet 4 of 5<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1f5c3a elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"a1f5c3a\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor99242 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor99242 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor99242 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor99242 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor99242 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor99242 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor99242\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">P02 Road Longsections, Sheet 5 of 5<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5374730 elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"5374730\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor102133 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor102133 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor102133 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor102133 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor102133 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor102133 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor102133\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">P01 Autotrack Layout Sheet 1 of 4<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a992e1a elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"a992e1a\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor112768 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor112768 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor112768 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor112768 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor112768 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor112768 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor112768\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">P01 Autotrack Layout Sheet 2 of 4<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f92ca44 elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"f92ca44\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor124418 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor124418 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor124418 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor124418 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor124418 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor124418 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor124418\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">P01 Autotrack Layout Sheet 3 of 4<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-508fc4c elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"508fc4c\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor132679 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor132679 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor132679 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor132679 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor132679 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor132679 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor132679\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">P01 Autotrack Layout Sheet 4 of 4<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-615fffd elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"615fffd\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor149680 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor149680 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor149680 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor149680 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor149680 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor149680 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor149680\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Vehicle Tracking<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7908aa elementor-widget elementor-widget-ucaddon_document_button\" data-id=\"a7908aa\" data-element_type=\"widget\" data-widget_type=\"ucaddon_document_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<!-- start Document Button -->\n\t\t\t<style type=\"text\/css\">\/* widget: Document Button *\/\n\n#uc_document_button_elementor154361 .document_frame_btn {\n  height: 64px;\n  background-color: #ffffff;\n  transition: 0.3s;\n}\n#uc_document_button_elementor154361 .document_frame_btn:hover {  \n  background-color: #555555;\n}\n#uc_document_button_elementor154361 .document_icon_btn {\n    position: relative;\n    padding-left: 26px;\n    top: calc((64px - 32px) * 0.5 + 0px);\n}\n#uc_document_button_elementor154361 .document_text_btn {\n  position: absolute;\n  top: 0px;\n  padding-left: 84px;\n  padding-right: 32px;\n  \n  height: 100%;\n  display: flex;\n  line-height: normal;\n  align-items: center;\n}\n#uc_document_button_elementor154361 .document_link_text_color {\n  color: #333333 !important;\n  transition: 0.3s;\n}\n#uc_document_button_elementor154361 .document_link_text_color:hover {\n  color: #FFFFFF !important;\n}\n\n<\/style>\n\n\t\t\t<a id=\"uc_document_button_elementor154361\" class=\"document_link_btn\" href=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/sample-drawing.pdf\" target=\"_blank\">\n  <div class=\"document_link_text_color document_frame_btn\">\n    <div class=\"document_icon_btn\">\n     \t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" width=\"32\" height=\"32\">\n    <\/div>\n    <div class=\"db_txt_typo document_text_btn\">Watermain Layout<\/div>\n  <\/div>\n<\/a>\n\t\t\t<!-- end Document Button -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bc1d65 elementor-widget elementor-widget-spacer\" data-id=\"6bc1d65\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e5716d elementor-widget elementor-widget-spacer\" data-id=\"3e5716d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Engineering P01 Proposed Site Layout P02 Proposed Site Drainage P02 Watermain Layout P01 Proposed Site Levels P02 Road Longsections, Sheet 1 of 5 P02 Road Longsections, Sheet 2 of 5 P02 Road Longsections, Sheet 3 of 5 P02 Road Longsections, Sheet 4 of 5 P02 Road Longsections, Sheet 5 of 5 P01 Autotrack Layout Sheet [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-642","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Drawings - Engineering - LRD Website Template<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lrdwebsite.ie\/template1\/drawings-engineering\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Drawings - Engineering - LRD Website Template\" \/>\n<meta property=\"og:description\" content=\"Engineering P01 Proposed Site Layout P02 Proposed Site Drainage P02 Watermain Layout P01 Proposed Site Levels P02 Road Longsections, Sheet 1 of 5 P02 Road Longsections, Sheet 2 of 5 P02 Road Longsections, Sheet 3 of 5 P02 Road Longsections, Sheet 4 of 5 P02 Road Longsections, Sheet 5 of 5 P01 Autotrack Layout Sheet [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lrdwebsite.ie\/template1\/drawings-engineering\/\" \/>\n<meta property=\"og:site_name\" content=\"LRD Website Template\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-11T01:30:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lrdwebsite.ie\/template1\/drawings-engineering\/\",\"url\":\"https:\/\/lrdwebsite.ie\/template1\/drawings-engineering\/\",\"name\":\"Drawings - Engineering - LRD Website Template\",\"isPartOf\":{\"@id\":\"https:\/\/lrdwebsite.ie\/template1\/#website\"},\"datePublished\":\"2022-08-31T15:54:56+00:00\",\"dateModified\":\"2022-11-11T01:30:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lrdwebsite.ie\/template1\/drawings-engineering\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lrdwebsite.ie\/template1\/drawings-engineering\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lrdwebsite.ie\/template1\/drawings-engineering\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/lrdwebsite.ie\/template1\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Drawings &#8211; Engineering\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lrdwebsite.ie\/template1\/#website\",\"url\":\"https:\/\/lrdwebsite.ie\/template1\/\",\"name\":\"LRD Website Template\",\"description\":\"LRD Website Template\",\"publisher\":{\"@id\":\"https:\/\/lrdwebsite.ie\/template1\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lrdwebsite.ie\/template1\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lrdwebsite.ie\/template1\/#organization\",\"name\":\"LRD Website Template\",\"url\":\"https:\/\/lrdwebsite.ie\/template1\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lrdwebsite.ie\/template1\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/Logo-top.png\",\"contentUrl\":\"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/Logo-top.png\",\"width\":100,\"height\":21,\"caption\":\"LRD Website Template\"},\"image\":{\"@id\":\"https:\/\/lrdwebsite.ie\/template1\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Drawings - Engineering - LRD Website Template","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lrdwebsite.ie\/template1\/drawings-engineering\/","og_locale":"en_US","og_type":"article","og_title":"Drawings - Engineering - LRD Website Template","og_description":"Engineering P01 Proposed Site Layout P02 Proposed Site Drainage P02 Watermain Layout P01 Proposed Site Levels P02 Road Longsections, Sheet 1 of 5 P02 Road Longsections, Sheet 2 of 5 P02 Road Longsections, Sheet 3 of 5 P02 Road Longsections, Sheet 4 of 5 P02 Road Longsections, Sheet 5 of 5 P01 Autotrack Layout Sheet [&hellip;]","og_url":"https:\/\/lrdwebsite.ie\/template1\/drawings-engineering\/","og_site_name":"LRD Website Template","article_modified_time":"2022-11-11T01:30:14+00:00","og_image":[{"url":"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/08\/pdf.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lrdwebsite.ie\/template1\/drawings-engineering\/","url":"https:\/\/lrdwebsite.ie\/template1\/drawings-engineering\/","name":"Drawings - Engineering - LRD Website Template","isPartOf":{"@id":"https:\/\/lrdwebsite.ie\/template1\/#website"},"datePublished":"2022-08-31T15:54:56+00:00","dateModified":"2022-11-11T01:30:14+00:00","breadcrumb":{"@id":"https:\/\/lrdwebsite.ie\/template1\/drawings-engineering\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lrdwebsite.ie\/template1\/drawings-engineering\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lrdwebsite.ie\/template1\/drawings-engineering\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lrdwebsite.ie\/template1\/"},{"@type":"ListItem","position":2,"name":"Drawings &#8211; Engineering"}]},{"@type":"WebSite","@id":"https:\/\/lrdwebsite.ie\/template1\/#website","url":"https:\/\/lrdwebsite.ie\/template1\/","name":"LRD Website Template","description":"LRD Website Template","publisher":{"@id":"https:\/\/lrdwebsite.ie\/template1\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lrdwebsite.ie\/template1\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lrdwebsite.ie\/template1\/#organization","name":"LRD Website Template","url":"https:\/\/lrdwebsite.ie\/template1\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lrdwebsite.ie\/template1\/#\/schema\/logo\/image\/","url":"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/Logo-top.png","contentUrl":"https:\/\/lrdwebsite.ie\/template1\/wp-content\/uploads\/2022\/11\/Logo-top.png","width":100,"height":21,"caption":"LRD Website Template"},"image":{"@id":"https:\/\/lrdwebsite.ie\/template1\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lrdwebsite.ie\/template1\/wp-json\/wp\/v2\/pages\/642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lrdwebsite.ie\/template1\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lrdwebsite.ie\/template1\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lrdwebsite.ie\/template1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lrdwebsite.ie\/template1\/wp-json\/wp\/v2\/comments?post=642"}],"version-history":[{"count":8,"href":"https:\/\/lrdwebsite.ie\/template1\/wp-json\/wp\/v2\/pages\/642\/revisions"}],"predecessor-version":[{"id":852,"href":"https:\/\/lrdwebsite.ie\/template1\/wp-json\/wp\/v2\/pages\/642\/revisions\/852"}],"wp:attachment":[{"href":"https:\/\/lrdwebsite.ie\/template1\/wp-json\/wp\/v2\/media?parent=642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}